{"id":3235,"count":1,"description":"","link":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/","name":"Copenhagen Tour","slug":"copenhagen-tour","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Copenhagen Tour Archives - A Bavarian Sojourn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copenhagen Tour Archives - A Bavarian Sojourn\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"A Bavarian Sojourn\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/\",\"url\":\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/\",\"name\":\"Copenhagen Tour Archives - A Bavarian Sojourn\",\"isPartOf\":{\"@id\":\"https:\/\/www.thesojournseries.com\/bavaria\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.thesojournseries.com\/bavaria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Copenhagen Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.thesojournseries.com\/bavaria\/#website\",\"url\":\"https:\/\/www.thesojournseries.com\/bavaria\/\",\"name\":\"A Bavarian Sojourn\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.thesojournseries.com\/bavaria\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copenhagen Tour Archives - A Bavarian Sojourn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/","og_locale":"en_US","og_type":"article","og_title":"Copenhagen Tour Archives - A Bavarian Sojourn","og_url":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/","og_site_name":"A Bavarian Sojourn","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/","url":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/","name":"Copenhagen Tour Archives - A Bavarian Sojourn","isPartOf":{"@id":"https:\/\/www.thesojournseries.com\/bavaria\/#website"},"breadcrumb":{"@id":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/www.thesojournseries.com\/bavaria\/tag\/copenhagen-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thesojournseries.com\/bavaria\/"},{"@type":"ListItem","position":2,"name":"Copenhagen Tour"}]},{"@type":"WebSite","@id":"https:\/\/www.thesojournseries.com\/bavaria\/#website","url":"https:\/\/www.thesojournseries.com\/bavaria\/","name":"A Bavarian Sojourn","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thesojournseries.com\/bavaria\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/www.thesojournseries.com\/bavaria\/wp-json\/wp\/v2\/tags\/3235"}],"collection":[{"href":"http:\/\/www.thesojournseries.com\/bavaria\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.thesojournseries.com\/bavaria\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.thesojournseries.com\/bavaria\/wp-json\/wp\/v2\/posts?tags=3235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}